{"id":4780,"date":"2019-04-19T18:06:01","date_gmt":"2019-04-19T16:06:01","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=oeuvres&#038;p=4780"},"modified":"2020-03-23T14:32:43","modified_gmt":"2020-03-23T13:32:43","slug":"w-ici-et-la-les-chevaux-roses-hennissent","status":"publish","type":"oeuvres","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/","title":{"rendered":"W \/ Ici et l\u00e0 les chevaux roses hennissent"},"content":{"rendered":"<p>W \/ Ici et l\u00e0 les chevaux roses hennissent<br \/>\nW \/ Li caju la sa ushi rosa batzechi<\/p>\n<p>2017<\/p>\n<p>coeur de palme, laiton<\/p>\n<p>53,5 x 56 x 25 cm &#8211; socle 70 x 58 cm<\/p>\n","protected":false},"featured_media":4715,"menu_order":0,"template":"","class_list":["post-4780","oeuvres","type-oeuvres","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seulgi Lee | W \/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Seulgi Lee, &quot;W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi&quot;, 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Seulgi Lee | W \/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Seulgi Lee, &quot;W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi&quot;, 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-23T13:32:43+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/Seulgi_Lee_W_chevaux.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/\",\"name\":\"Seulgi Lee | W \\\/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/Seulgi_Lee_W_chevaux.jpg\",\"datePublished\":\"2019-04-19T16:06:01+00:00\",\"dateModified\":\"2020-03-23T13:32:43+00:00\",\"description\":\"Seulgi Lee, \\\"W \\\/ Ici et l\u00e0 les chevaux roses hennissent ; W \\\/ Li caju la sa ushi rosa batzechi\\\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/Seulgi_Lee_W_chevaux.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/Seulgi_Lee_W_chevaux.jpg\",\"width\":900,\"height\":1275,\"caption\":\"Seulgi Lee, \\\"W \\\/ Ici et l\u00e0 les chevaux roses hennissent ; W \\\/ Li caju la sa ushi rosa batzechi\\\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/w-ici-et-la-les-chevaux-roses-hennissent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artworks\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"W \\\/ Ici et l\u00e0 les chevaux roses hennissent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seulgi Lee | W \/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain","description":"Seulgi Lee, \"W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/","og_locale":"fr_FR","og_type":"article","og_title":"Seulgi Lee | W \/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain","og_description":"Seulgi Lee, \"W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/","og_site_name":"Jousse-entreprise | Art Contemporain","article_modified_time":"2020-03-23T13:32:43+00:00","og_image":[{"width":900,"height":1275,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/Seulgi_Lee_W_chevaux.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/","name":"Seulgi Lee | W \/ Ici et l\u00e0 les chevaux roses hennissent | Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/Seulgi_Lee_W_chevaux.jpg","datePublished":"2019-04-19T16:06:01+00:00","dateModified":"2020-03-23T13:32:43+00:00","description":"Seulgi Lee, \"W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm - Galerie Jousse Entreprise","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/Seulgi_Lee_W_chevaux.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/Seulgi_Lee_W_chevaux.jpg","width":900,"height":1275,"caption":"Seulgi Lee, \"W \/ Ici et l\u00e0 les chevaux roses hennissent ; W \/ Li caju la sa ushi rosa batzechi\", 2017, coeur de palme, laiton, 53,5 x 56 x 25 cm - socle 70 x 58 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/w-ici-et-la-les-chevaux-roses-hennissent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Artworks","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/"},{"@type":"ListItem","position":3,"name":"W \/ Ici et l\u00e0 les chevaux roses hennissent"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/4780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/oeuvres"}],"version-history":[{"count":1,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/4780\/revisions"}],"predecessor-version":[{"id":4781,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/4780\/revisions\/4781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/4715"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=4780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}