{"id":3598,"date":"2019-04-05T17:25:29","date_gmt":"2019-04-05T15:25:29","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=oeuvres&#038;p=3598"},"modified":"2020-03-27T14:17:26","modified_gmt":"2020-03-27T13:17:26","slug":"kurdish-lovers","status":"publish","type":"oeuvres","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/","title":{"rendered":"Kurdish Lovers"},"content":{"rendered":"<p>2010<\/p>\n<p>documentary<\/p>\n<p>video HD 4:3<\/p>\n<p>95&prime;<\/p>\n<p>languages: kurdish, turkish, french \/ Subtitles : english, french, finnish<\/p>\n<p>production: les films du pr\u00e9sent, avanton oy production, 24 images<\/p>\n<p>&nbsp;<\/p>\n<p>The Kurdish lover is Oktay, the man with whom I share my life. We went to his village in Kurdistan, a region brought to a standstill by war. At this place, loving someone can become confused with having a hold over them. It is with humor that the characters featured in this film find ways, within their community, to affirm that they truly exist. A shaman goes into trance in front of the television, a hermit dreams of marriage, a shepherdess wants to leave the top of the mountain, soldiers watch over the village, a man from Europe goes off to request the hand of a young woman. It is through these situations that we discover the reality of families doing what they can to find a way of living together, to take the best \u2013 or the worst \u2013 from each moment. \u201c<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":3599,"menu_order":0,"template":"","class_list":["post-3598","oeuvres","type-oeuvres","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Clarisse Hahn, &quot;Kurdish Lovers&quot;, 2010, documentary, video HD 4:3, 95&#039;, production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Clarisse Hahn, &quot;Kurdish Lovers&quot;, 2010, documentary, video HD 4:3, 95&#039;, production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-27T13:17:26+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/clarisse_hahn_kurdishlovers.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/\",\"name\":\"Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/clarisse_hahn_kurdishlovers.jpg\",\"datePublished\":\"2019-04-05T15:25:29+00:00\",\"dateModified\":\"2020-03-27T13:17:26+00:00\",\"description\":\"Clarisse Hahn, \\\"Kurdish Lovers\\\", 2010, documentary, video HD 4:3, 95', production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/clarisse_hahn_kurdishlovers.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/04\\\/clarisse_hahn_kurdishlovers.jpg\",\"width\":598,\"height\":478,\"caption\":\"clarisse_hahn_kurdishlovers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/kurdish-lovers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artworks\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kurdish Lovers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain","description":"Clarisse Hahn, \"Kurdish Lovers\", 2010, documentary, video HD 4:3, 95', production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/","og_locale":"fr_FR","og_type":"article","og_title":"Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain","og_description":"Clarisse Hahn, \"Kurdish Lovers\", 2010, documentary, video HD 4:3, 95', production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/","og_site_name":"Jousse-entreprise | Art Contemporain","article_modified_time":"2020-03-27T13:17:26+00:00","og_image":[{"width":598,"height":478,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/clarisse_hahn_kurdishlovers.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/","name":"Clarisse Hahn | Kurdish Lovers | Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/clarisse_hahn_kurdishlovers.jpg","datePublished":"2019-04-05T15:25:29+00:00","dateModified":"2020-03-27T13:17:26+00:00","description":"Clarisse Hahn, \"Kurdish Lovers\", 2010, documentary, video HD 4:3, 95', production: les films du pr\u00e9sent, avanton oy production, 24 images - Galerie Jousse Entreprise","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/clarisse_hahn_kurdishlovers.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/04\/clarisse_hahn_kurdishlovers.jpg","width":598,"height":478,"caption":"clarisse_hahn_kurdishlovers"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/kurdish-lovers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Artworks","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/"},{"@type":"ListItem","position":3,"name":"Kurdish Lovers"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/3598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/oeuvres"}],"version-history":[{"count":5,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/3598\/revisions"}],"predecessor-version":[{"id":9253,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/3598\/revisions\/9253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/3599"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}