{"id":22888,"date":"2025-10-14T17:08:22","date_gmt":"2025-10-14T15:08:22","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=oeuvres&#038;p=22888"},"modified":"2025-10-14T17:08:22","modified_gmt":"2025-10-14T15:08:22","slug":"distraction","status":"publish","type":"oeuvres","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/","title":{"rendered":"Distraction"},"content":{"rendered":"<p>2025<\/p>\n<p>feutre sur papier<\/p>\n<p>21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9)<\/p>\n","protected":false},"featured_media":22889,"menu_order":0,"template":"","class_list":["post-22888","oeuvres","type-oeuvres","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Madeleine Roger-Lacan, &quot;Distraction&quot;, 2025, feutre sur papier, 21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Madeleine Roger-Lacan, &quot;Distraction&quot;, 2025, feutre sur papier, 21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/10\/LustLoneliness-26-scaled.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"2031\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/\",\"name\":\"Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/LustLoneliness-26-scaled.jpg\",\"datePublished\":\"2025-10-14T15:08:22+00:00\",\"description\":\"Madeleine Roger-Lacan, \\\"Distraction\\\", 2025, feutre sur papier, 21 x 29,7 cm \\\/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/LustLoneliness-26-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/10\\\/LustLoneliness-26-scaled.jpg\",\"width\":2560,\"height\":2031},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/distraction\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artworks\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Distraction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain","description":"Madeleine Roger-Lacan, \"Distraction\", 2025, feutre sur papier, 21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/","og_locale":"fr_FR","og_type":"article","og_title":"Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain","og_description":"Madeleine Roger-Lacan, \"Distraction\", 2025, feutre sur papier, 21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/","og_site_name":"Jousse-entreprise | Art Contemporain","og_image":[{"width":2560,"height":2031,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/10\/LustLoneliness-26-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/","name":"Madeleine Roger-Lacan | Distraction | Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/10\/LustLoneliness-26-scaled.jpg","datePublished":"2025-10-14T15:08:22+00:00","description":"Madeleine Roger-Lacan, \"Distraction\", 2025, feutre sur papier, 21 x 29,7 cm \/ 30,2 x 38,7 cm (encadr\u00e9) - Galerie Jousse Entreprise, Paris","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/10\/LustLoneliness-26-scaled.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/10\/LustLoneliness-26-scaled.jpg","width":2560,"height":2031},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/distraction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Artworks","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/"},{"@type":"ListItem","position":3,"name":"Distraction"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/22888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/oeuvres"}],"version-history":[{"count":1,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/22888\/revisions"}],"predecessor-version":[{"id":22890,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/22888\/revisions\/22890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/22889"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=22888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}