{"id":21793,"date":"2025-03-28T15:08:42","date_gmt":"2025-03-28T14:08:42","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=oeuvres&#038;p=21793"},"modified":"2025-03-28T15:08:42","modified_gmt":"2025-03-28T14:08:42","slug":"la-huaca-pleure","status":"publish","type":"oeuvres","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/","title":{"rendered":"La huaca pleure"},"content":{"rendered":"<div class=\"page\" title=\"Page 5\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Un ensemble de quatre vide\u0301os forment l\u2019installation <em>La huaca pleure<\/em> (2024). Des galets glane\u0301s sur les rives d\u2019une rivie\u0300re vosgienne, la Doller, et des le\u0301s de papier kraft rappelant la couleur du de\u0301sert pe\u0301ruvien, cre\u0301ent un dispositif pour accueillir les vide\u0301os.<\/p>\n<\/div>\n<div class=\"column\">\n<p><i>La huaca pleure, avec Marion et Jos\u00e9 Luis<\/i><\/p>\n<p>2024<\/p>\n<p>Vid\u00e9o 4K<\/p>\n<p>13min 40sec<\/p>\n<p>&nbsp;<\/p>\n<p><em>La huaca pleure, avec Terreco et la Mesa<\/em><\/p>\n<\/div>\n<p>2024<\/p>\n<p>Vide\u0301o 4K transfert HD<\/p>\n<p>6 min 34 sec<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Deux vide\u0301os retracent diffe\u0301rentes e\u0301tapes lie\u0301es a\u0300 la <em>huaqueri\u0301a<\/em> (fouille clandestine), auxquelles Louidgi Beltrame a pu assister sur le site arche\u0301ologique de Pakatnamu dans le de\u0301sert co\u0302tier du nord du Pe\u0301rou. Aide\u0301s par la consommation de coca et de tabac, les <em>huaqueros<\/em>, Terreco, Oscar, Marlon et Jose\u0301 Luis, pratiquent la divination et interrogent la <em>huaca<\/em> pour trouver l\u2019emplacement des tombes. Ensuite, ceux-ci sondent le sol e\u0301quipe\u0301s de baquetas et, lorsqu\u2019ils pensent avoir localise\u0301 l\u2019emplacement des se\u0301pultures, ils creusent un ou plusieurs trous afin de retrouver les objets rituels. On dit que la huaca pleure lorsque des larmes de sable commencent a\u0300 couler sur les bords de la tombe exhume\u0301e. Celle-ci menac\u0327ant de s\u2019effondrer sur les fouilleurs, il est temps de la quitter.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><i>La huaca pleure, avec la Mesa<\/i><\/p>\n<p>2024<\/p>\n<p>Vid\u00e9o 4K transfert HD<\/p>\n<p>10min 19sec6min 46 sec<\/p>\n<p>Une troisie\u0300me vide\u0301o &#8211;\u00a0en boucle sur e\u0301cran e\u0301cran plat montre un exemple de mesa (table en espagnol) chez Terreco, dans la communaute\u0301 rurale de Jequetepeque. Cette mesa, e\u0301quivalent a\u0300 un autel syncre\u0301tique, est installe\u0301e dans son espace domestique sur un canape\u0301 et est constitue\u0301e des diffe\u0301rents tre\u0301sors collecte\u0301s lors des fouilles du <em>huaquero<\/em>. Elle comporte notamment un ensemble de cra\u0302nes humains qu\u2019il utilise lors de rituels de gue\u0301rison.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><i>La huaca pleure, avec les huacos<\/i><\/p>\n<p>2024<\/p>\n<p>Vid\u00e9o 4K transfert HD<\/p>\n<p>10min 19sec<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Une quatrie\u0300me vide\u0301o montre des <em>huacos<\/em> (ce\u0301ramiques rituelles pre\u0301colombiennes) en rotation. Ces ce\u0301ramiques sont issues d\u2019une collection locale, prive\u0301e et semi-clandestine de pie\u0300ces achete\u0301es au fil des anne\u0301es a\u0300 des huaqueros de la re\u0301gion de Pacasmayo par le pe\u0300re du proprie\u0301taire actuel.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":21794,"menu_order":0,"template":"","class_list":["post-21793","oeuvres","type-oeuvres","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La huaca pleure - Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"La huaca pleure - Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Un ensemble de quatre vide\u0301os forment l\u2019installation La huaca pleure (2024). Des galets glane\u0301s sur les rives d\u2019une rivie\u0300re vosgienne, la Doller, et des le\u0301s de papier kraft rappelant la couleur du de\u0301sert pe\u0301ruvien, cre\u0301ent un dispositif pour accueillir les vide\u0301os. La huaca pleure, avec Marion et Jos\u00e9 Luis 2024 Vid\u00e9o 4K 13min 40sec &nbsp; [&hellip;]\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/03\/0173-scaled.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1727\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/\",\"name\":\"La huaca pleure - Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/0173-scaled.jpg\",\"datePublished\":\"2025-03-28T14:08:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/0173-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/0173-scaled.jpg\",\"width\":2560,\"height\":1727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/la-huaca-pleure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artworks\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La huaca pleure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La huaca pleure - Jousse-entreprise | Art Contemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/","og_locale":"fr_FR","og_type":"article","og_title":"La huaca pleure - Jousse-entreprise | Art Contemporain","og_description":"Un ensemble de quatre vide\u0301os forment l\u2019installation La huaca pleure (2024). Des galets glane\u0301s sur les rives d\u2019une rivie\u0300re vosgienne, la Doller, et des le\u0301s de papier kraft rappelant la couleur du de\u0301sert pe\u0301ruvien, cre\u0301ent un dispositif pour accueillir les vide\u0301os. La huaca pleure, avec Marion et Jos\u00e9 Luis 2024 Vid\u00e9o 4K 13min 40sec &nbsp; [&hellip;]","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/","og_site_name":"Jousse-entreprise | Art Contemporain","og_image":[{"width":2560,"height":1727,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/03\/0173-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/","name":"La huaca pleure - Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/03\/0173-scaled.jpg","datePublished":"2025-03-28T14:08:42+00:00","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/03\/0173-scaled.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/03\/0173-scaled.jpg","width":2560,"height":1727},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/la-huaca-pleure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Artworks","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/"},{"@type":"ListItem","position":3,"name":"La huaca pleure"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/21793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/oeuvres"}],"version-history":[{"count":1,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/21793\/revisions"}],"predecessor-version":[{"id":21799,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/21793\/revisions\/21799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/21794"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=21793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}