{"id":13477,"date":"2021-06-03T17:34:30","date_gmt":"2021-06-03T15:34:30","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=oeuvres&#038;p=13477"},"modified":"2021-06-03T17:34:30","modified_gmt":"2021-06-03T15:34:30","slug":"le-couple","status":"publish","type":"oeuvres","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/","title":{"rendered":"Le couple"},"content":{"rendered":"<p>2021<\/p>\n<p>huile sur toile<\/p>\n<p>62 x 83 cm<\/p>\n","protected":false},"featured_media":13478,"menu_order":0,"template":"","class_list":["post-13477","oeuvres","type-oeuvres","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Nathana\u00eblle Herbelin, &quot;Le couple&quot;, 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Nathana\u00eblle Herbelin, &quot;Le couple&quot;, 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2021\/06\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1903\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/\",\"name\":\"Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg\",\"datePublished\":\"2021-06-03T15:34:30+00:00\",\"description\":\"Nathana\u00eblle Herbelin, \\\"Le couple\\\", 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/06\\\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg\",\"width\":2560,\"height\":1903,\"caption\":\"Le couple, 2021, huile sur toile, 62 x 83 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/oeuvres\\\/le-couple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artworks\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/en\\\/oeuvres\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le couple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain","description":"Nathana\u00eblle Herbelin, \"Le couple\", 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/","og_locale":"fr_FR","og_type":"article","og_title":"Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain","og_description":"Nathana\u00eblle Herbelin, \"Le couple\", 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/","og_site_name":"Jousse-entreprise | Art Contemporain","og_image":[{"width":2560,"height":1903,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2021\/06\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/","name":"Nathana\u00eblle Herbelin | Le couple | Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2021\/06\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg","datePublished":"2021-06-03T15:34:30+00:00","description":"Nathana\u00eblle Herbelin, \"Le couple\", 2021, huile sur toile, 62 x 83 cm - Galerie Jousse Entreprise","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2021\/06\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2021\/06\/Le-couple-2021-huile-sur-toile-62-x-83-cm-scaled.jpg","width":2560,"height":1903,"caption":"Le couple, 2021, huile sur toile, 62 x 83 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/oeuvres\/le-couple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Artworks","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/en\/oeuvres\/"},{"@type":"ListItem","position":3,"name":"Le couple"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/13477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/oeuvres"}],"version-history":[{"count":1,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/13477\/revisions"}],"predecessor-version":[{"id":13479,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/oeuvres\/13477\/revisions\/13479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/13478"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=13477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}