{"id":23595,"date":"2026-03-19T12:15:10","date_gmt":"2026-03-19T11:15:10","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=expositions&#038;p=23595"},"modified":"2026-03-19T12:15:10","modified_gmt":"2026-03-19T11:15:10","slug":"clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart","status":"publish","type":"expositions","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/","title":{"rendered":"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l&rsquo;art"},"content":{"rendered":"<p>Nous avons le plaisir d&rsquo;annoncer la participation de Clarisse Hahn \u00e0 l&rsquo;exposition collective \u00ab <em>La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb <\/em>\u00e0 l&rsquo;espace Topographie de l&rsquo;art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d&rsquo;exposition Fran\u00e7ois Michaud.<\/p>\n<p class=\"p1\">L&rsquo;exposition \u00ab <em>La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de\u00a0tilleul qui tombe<\/em>\u00a0\u00bb r\u00e9unit 18 artistes qui explorent la po\u00e9sie du quotidien,\u00a0improvisant avec des mat\u00e9riaux simples et refusant le spectaculaire.<\/p>\n<p class=\"p1\">Con\u00e7ue comme un jeu de construction \u00e0 Topographie de l\u2019art, l\u2019exposition\u00a0pr\u00e9sente des \u0153uvres individuelles qui refl\u00e8tent souvent \u00ab le jeu et le\u00a0divertissement \u00bb avec une certaine gravit\u00e9. Plusieurs d\u2019entre elles abordent la\u00a0notion de paradoxe : \u00e0 la fois ludiques et significatives.<\/p>\n<p class=\"p1\">La phrase de Mathieu Yon, philosophe, po\u00e8te et mara\u00eecher, choisie pour titre du\u00a0projet, \u00e9voque la fragilit\u00e9 de l\u2019artiste tout autant que la force de sa voix\u00a0dans notre soci\u00e9t\u00e9.<\/p>\n<p class=\"p1\">Sculptures en Lego, \u0153uvres en fils, vid\u00e9os, photographies, peintures et\u00a0dessins dialoguent entre eux comme on saute sur les cases d\u2019une marelle ou\u00a0comme on se r\u00e9pond dans un cadavre exquis.<\/p>\n","protected":false},"featured_media":23596,"menu_order":0,"template":"","class_list":["post-23595","expositions","type-expositions","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l&#039;art | Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Nous avons le plaisir d&#039;annoncer la participation de Clarisse Hahn \u00e0 l&#039;exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l&#039;espace Topographie de l&#039;art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d&#039;exposition Fran\u00e7ois Michaud.\u00a0\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun\u00b7e-poete\u00b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l&#039;art | Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Nous avons le plaisir d&#039;annoncer la participation de Clarisse Hahn \u00e0 l&#039;exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l&#039;espace Topographie de l&#039;art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d&#039;exposition Fran\u00e7ois Michaud.\u00a0\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun\u00b7e-poete\u00b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2026\/03\/12-rancheros-copie.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/\",\"name\":\"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l'art | Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/12-rancheros-copie.jpg\",\"datePublished\":\"2026-03-19T11:15:10+00:00\",\"description\":\"Nous avons le plaisir d'annoncer la participation de Clarisse Hahn \u00e0 l'exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l'espace Topographie de l'art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d'exposition Fran\u00e7ois Michaud.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/12-rancheros-copie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/12-rancheros-copie.jpg\",\"width\":800,\"height\":483,\"caption\":\"clarissehahn_rancheros_jousseentreprise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expositions\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l&rsquo;art\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l'art | Jousse-entreprise | Art Contemporain","description":"Nous avons le plaisir d'annoncer la participation de Clarisse Hahn \u00e0 l'exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l'espace Topographie de l'art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d'exposition Fran\u00e7ois Michaud.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun\u00b7e-poete\u00b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/","og_locale":"fr_FR","og_type":"article","og_title":"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l'art | Jousse-entreprise | Art Contemporain","og_description":"Nous avons le plaisir d'annoncer la participation de Clarisse Hahn \u00e0 l'exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l'espace Topographie de l'art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d'exposition Fran\u00e7ois Michaud.\u00a0","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun\u00b7e-poete\u00b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/","og_site_name":"Jousse-entreprise | Art Contemporain","og_image":[{"width":800,"height":483,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2026\/03\/12-rancheros-copie.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/","name":"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l'art | Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2026\/03\/12-rancheros-copie.jpg","datePublished":"2026-03-19T11:15:10+00:00","description":"Nous avons le plaisir d'annoncer la participation de Clarisse Hahn \u00e0 l'exposition collective \u00ab La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe \u00bb \u00e0 l'espace Topographie de l'art du 7 f\u00e9vrier au 11 avril 2026, sur une invitation du commissaire d'exposition Fran\u00e7ois Michaud.\u00a0","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2026\/03\/12-rancheros-copie.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2026\/03\/12-rancheros-copie.jpg","width":800,"height":483,"caption":"clarissehahn_rancheros_jousseentreprise"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/clarisse-hahn-la-mort-dun%c2%b7e-poete%c2%b7sse-fait-moins-de-bruit-quune-feuille-de-tilleul-qui-tombe-topographie-de-lart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Expositions","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/"},{"@type":"ListItem","position":3,"name":"CLARISSE HAHN | La mort d\u2019un\u00b7e po\u00e8te\u00b7sse fait moins de bruit qu\u2019une feuille de tilleul qui tombe | Topographie de l&rsquo;art"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/23595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/expositions"}],"version-history":[{"count":1,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/23595\/revisions"}],"predecessor-version":[{"id":23598,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/23595\/revisions\/23598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/23596"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=23595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}