{"id":22488,"date":"2025-07-16T17:58:31","date_gmt":"2025-07-16T15:58:31","guid":{"rendered":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?post_type=expositions&#038;p=22488"},"modified":"2025-11-29T13:06:48","modified_gmt":"2025-11-29T12:06:48","slug":"madeleine-roger-lacan","status":"publish","type":"expositions","link":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/","title":{"rendered":"MADELEINE ROGER-LACAN | Lust and Loneliness"},"content":{"rendered":"<p>Nous avons le plaisir d&rsquo;annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00ab\u00a0Lust and Loneliness\u00a0\u00bb \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris) du 11 octobre au 29 novembre 2025 (fermeture le 1er novembre et 11 novembre).<\/p>\n<p>L\u2019exposition <i>Lust and Loneliness <\/i>de Madeleine Roger-Lacan se lit comme un r\u00e9cit \u2013 une autofiction \u2013 faisant \u00e9cho \u00e0 l\u2019audace de l\u2019ouvrage<i> Body Work<\/i> de Melissa Febos, tout en s\u2019\u00e9lan\u00e7ant sans crainte vers une f\u00e9minit\u00e9 boulevers\u00e9e. Effusive dans son expression de la rage et du d\u00e9sir f\u00e9minin, l\u2019artiste repr\u00e9sente les lieux o\u00f9 la sexualit\u00e9 f\u00e9minine se d\u00e9lie, et o\u00f9 le chaos de la maternit\u00e9 se change en monstruosit\u00e9. L\u2019univers en expansion de Madeleine Roger-Lacan s\u2019incorpore dans des paysages urbains : le lit d\u2019un amant, une rencontre de rue violente ou encore le studio d\u2019une peintre, per\u00e7u comme une aire de jeux nocturne. Sa cartographie fertile, brouillonn\u00e9e par fragments, s\u2019\u00e9tend du textile \u00e0 la peinture, couvre la Ville Lumi\u00e8re et les \u00e9crans digitaux dans un r\u00e9seau de selfies, de Street views et de ChatGPT.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Comme si elle enfon\u00e7ait ses talons dans des \u00e9triers de m\u00e9tal glac\u00e9, pr\u00eate \u00e0 accoucher d\u2019une famille de petits tableaux,\u00a0<i>Robe Polygame<\/i> (2025) s\u2019appuie contre le mur de la galerie et \u00e9carte largement ses cuisses. Ses formes corpulentes d\u00e9bordent de m\u00e9moire et d\u2019envie. Assemblage de dix toiles uniques, cette \u0153uvre se compose d\u2019extraits d\u2019archives personnelles, patiemment reconstitu\u00e9s par l\u2019artiste. Une toile en forme d\u2019hexagone fran\u00e7ais renvers\u00e9 et couverte de morceaux d\u2019un miroir bris\u00e9, brille l\u00e0 o\u00f9 le c\u0153ur de cette robe se trouverait. C\u2019est un \u00ab Miroir, mon beau Miroir \u00bb fractur\u00e9, r\u00e9pondant \u00e0 la question d\u2019Hans Ulrich Obrist dans son <i>Questionnaire<\/i> \u00ab Est-ce que le miroir est bris\u00e9 ? \u00bb. Oui, compl\u00e8tement. \u00c0 la mani\u00e8re des <i>Tableaux \u00c9clat\u00e9s<\/i> de Niki de Saint Phalle, r\u00e9alis\u00e9s apr\u00e8s la perte de Jean Tinguely et pens\u00e9s comme des moyens de \u00ab r\u00e9assembler les pi\u00e8ces \u00e9parpill\u00e9es de mon \u00e2me et ma psych\u00e9 \u00bb, ces flashbacks analogiques des sept derni\u00e8res ann\u00e9es de Madeleine Roger Lacan annoncent un moment de cr\u00e9ation. Les yeux grands ouverts et le pinceau huil\u00e9, l\u2019artiste s\u2019expose seule. Elle met en sc\u00e8ne des images qui d\u00e9rivent vers le fantasme, caressant les corps masculins, glissant hors de la vie ou se dressant dans son anticipation. La b\u00e9ance caverneuse qui s\u2019ouvre entre les jambes de cette figure quasi-d\u00e9ifi\u00e9e anticipe non seulement la naissance vaginale mais aussi le plaisir polygame primaire. Cr\u00e9ant un kal\u00e9idoscope de possibilit\u00e9s pour la figuration des hommes et des femmes, la peinture de l\u2019artiste ne se limite pas \u00e0 une forme maternelle, elle r\u00e8gne sur un royaume au-del\u00e0 du binaire \u2013 au-del\u00e0 m\u00eame du seuil de la mort.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Cet \u00e9t\u00e9, Madeleine Roger-Lacan a voyag\u00e9 \u00e0 travers l\u2019Italie (terre de la \u00ab Mecque \u00bb architecturale de Niki de Saint Phalle, <i>Il Giardino dei Tarocchi<\/i>), faisant un p\u00e8lerinage vers <i>l\u2019Annonciation<\/i> de Fra Angelico tout en rendant visite \u00e0 la derni\u00e8re exposition de Tracey Emin \u00e0 Florence. Dans son sac \u00e0 dos, elle transportait trois petites \u0153uvres, pr\u00e9sent\u00e9es ici : <i>Frustration<\/i>, <i>Maintenant (quelque chose de perdu)<\/i> et <i>Le Hasard <\/i>(les deux derni\u00e8res \u00e9tant de lourdes huiles sur bois). De retour \u00e0 Paris, ces \u0153uvres ont rejoint cinq autres toiles, ainsi que trois \u0153uvres sur papier et une photographie couleur r\u00e9v\u00e9latrice, chacune communiquant avec l\u2019autre, d\u2019apr\u00e8s l\u2019artiste, comme des fr\u00e8res et s\u0153urs pourraient le faire.<span class=\"Apple-converted-space\"><br \/>\n<\/span>Se trouvaient \u00e9galement dans ce sac de voyage (que j\u2019imagine comme un ut\u00e9rus, o\u00f9 cette exposition s\u2019est form\u00e9e \u00e0 mesure que la fille de Madeleine Roger-Lacan grandissait dans son ventre), <i>Oser le nu<\/i> de Camille Morineau, dans lequel l\u2019abbesse du XIIe si\u00e8cle Hildegard von Bingen est reconnue comme la premi\u00e8re autrice d\u2018un nu masculin de l\u2019histoire ; <i>Sex at Dawn <\/i>de Christopher Ryan et Calcida Jeth\u00e1, une r\u00e9vision des croyances \u00e9tablies sur la nature sexuelle des hommes et des femmes ;<span class=\"Apple-converted-space\">\u00a0<\/span>ainsi que <i>Vie ? ou Th\u00e9\u00e2tre ?<\/i> de Charlottte Salomon, un corpus d\u2019\u0153uvre extr\u00eamement inspirant cr\u00e9\u00e9 par une artiste en exil faisant face \u00e0 l\u2019in\u00e9vitable r\u00e9gime Nazi dans le sud de la France. Ces titres r\u00e9pondent \u00e0 mes questions ainsi qu\u2019\u00e0 celles d\u2019Obrist, tout en r\u00e9affirmant cet adage d\u2019Oscar Wilde \u00ab C\u2019est ce que vous lisez quand vous n\u2019avez pas \u00e0 le faire qui d\u00e9termine ce que vous serez. \u00bb<\/p>\n<p><i>La Robe de ma fille\u00a0<\/i>rayonne au centre du long couloir arri\u00e8re de la galerie en transformation. Sur le trajet retour, la fresque<span class=\"Apple-converted-space\">\u00a0<\/span><i>La Peintre et l\u2019amoureuse<\/i> se d\u00e9ploie sur la cloison centrale. Ces derni\u00e8res \u0153uvres offrent une vision d\u2019un avenir d\u00e9nu\u00e9 de honte envers le<i> landau dans le couloir<\/i>*<span class=\"Apple-converted-space\">\u00a0 <\/span>\u2013 enti\u00e8rement lib\u00e9r\u00e9 de la croyance que artiste et m\u00e8re forment deux entit\u00e9s mutuellement exclusives. Tout sauf une robe de bapt\u00eame, cette silhouette taille enfant incorpore des sc\u00e8nes d\u2019extase sexuelle fortement color\u00e9es, rappelant les sauts fantastiques de l\u2019artiste entre l\u2019infantile et l\u2019\u00e9rotique. \u00ab Le changement qui compte dans la r\u00e9volution a lieu d\u2019abord dans l\u2019imagination \u00bb \u00e9crit Rebecca Solnit dans <i>Hope in the Dark<\/i>. Faisant autrefois r\u00e9f\u00e9rence aux \u00ab influences exclues \u00bb d\u2019une artiste comme ses \u00ab grands-m\u00e8res \u00bb, Solnit impose l\u2019imagination \u2013 le terrain du fantasme \u2013 comme un pouvoir. Pour Madeleine Roger-Lacan, l\u2019imagination vivace et sa transformation alchimique en composition et forme d\u00e9finissent son objectif ultime : \u00ab l\u2019acte de peindre et l\u2019acte d\u2019imaginer sont mes buts dans tout cela \u00bb. Inatteignables, sauf par le d\u00e9sir.<\/p>\n<p>Lillian Davies<br \/>\nTraduction : Lillian Davies, Rafa\u00ebl Deville<\/p>\n<p>*<i> The pram in the hall <\/i>est une expression de Cyril Connolly qui \u00e9nonce : \u00a0Il n\u2019y a pas d\u2019ennemi plus sombre \u00e0 l\u2019Art que le landau dans le couloir.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">\n","protected":false},"featured_media":22811,"menu_order":0,"template":"","class_list":["post-22488","expositions","type-expositions","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain<\/title>\n<meta name=\"description\" content=\"Nous avons le plaisir d&#039;annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Nous avons le plaisir d&#039;annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Jousse-entreprise | Art Contemporain\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T12:06:48+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/07\/LustLoneliness-01-scaled.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/\",\"name\":\"MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/LustLoneliness-01-scaled.jpg\",\"datePublished\":\"2025-07-16T15:58:31+00:00\",\"dateModified\":\"2025-11-29T12:06:48+00:00\",\"description\":\"Nous avons le plaisir d'annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/LustLoneliness-01-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/LustLoneliness-01-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/madeleine-roger-lacan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expositions\",\"item\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/fr\\\/expositions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MADELEINE ROGER-LACAN | Lust and Loneliness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#website\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#organization\",\"name\":\"Jousse-entreprise | Art Contemporain\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/01\\\/logoret.jpg\",\"width\":500,\"height\":200,\"caption\":\"Jousse-entreprise | Art Contemporain\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jousse-entreprise.com\\\/art-contemporain\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/galeriejousseentreprise\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain","description":"Nous avons le plaisir d'annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/","og_locale":"fr_FR","og_type":"article","og_title":"MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain","og_description":"Nous avons le plaisir d'annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).","og_url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/","og_site_name":"Jousse-entreprise | Art Contemporain","article_modified_time":"2025-11-29T12:06:48+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/07\/LustLoneliness-01-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/","name":"MADELEINE ROGER-LACAN | Lust and Loneliness - Jousse-entreprise | Art Contemporain","isPartOf":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/#primaryimage"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/07\/LustLoneliness-01-scaled.jpg","datePublished":"2025-07-16T15:58:31+00:00","dateModified":"2025-11-29T12:06:48+00:00","description":"Nous avons le plaisir d'annoncer la premi\u00e8re exposition personnelle de Madeleine Roger-Lacan \u00e0 la galerie Jousse Entreprise au 6 rue Saint-Claude (75003 Paris).","breadcrumb":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/#primaryimage","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/07\/LustLoneliness-01-scaled.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2025\/07\/LustLoneliness-01-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/madeleine-roger-lacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/"},{"@type":"ListItem","position":2,"name":"Expositions","item":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/fr\/expositions\/"},{"@type":"ListItem","position":3,"name":"MADELEINE ROGER-LACAN | Lust and Loneliness"}]},{"@type":"WebSite","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#website","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","name":"Jousse-entreprise | Art Contemporain","description":"","publisher":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#organization","name":"Jousse-entreprise | Art Contemporain","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/","url":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","contentUrl":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-content\/uploads\/sites\/4\/2019\/01\/logoret.jpg","width":500,"height":200,"caption":"Jousse-entreprise | Art Contemporain"},"image":{"@id":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/galeriejousseentreprise\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/22488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions"}],"about":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/types\/expositions"}],"version-history":[{"count":28,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/22488\/revisions"}],"predecessor-version":[{"id":23104,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/expositions\/22488\/revisions\/23104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media\/22811"}],"wp:attachment":[{"href":"https:\/\/www.jousse-entreprise.com\/art-contemporain\/wp-json\/wp\/v2\/media?parent=22488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}